{"id":1449,"date":"2018-03-10T18:59:11","date_gmt":"2018-03-10T17:59:11","guid":{"rendered":"http:\/\/www.p2-ingenieure.de\/wordpress\/?p=1449"},"modified":"2018-03-10T18:59:11","modified_gmt":"2018-03-10T17:59:11","slug":"was-eine-weg-bei-einem-dachausbau-beachten-sollte","status":"publish","type":"post","link":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/","title":{"rendered":"Was eine WEG bei einem Dachausbau beachten sollte"},"content":{"rendered":"<p><em>Erschienen im M\u00e4rz 2018 im Tagesspiegel<\/em><\/p>\n<h3>Was steht ins Haus?<\/h3>\n<p>Wir sind Eigent\u00fcmer einer gr\u00f6\u00dferen WEG in Mitte, das Geb\u00e4ude stammt aus den 1930er Jahren und verf\u00fcgt \u00fcber ein hohes Steildach, das sich zum Dachgeschossausbau eignet. Es gibt innerhalb der Eigent\u00fcmergemeinschaft zwei Lager, f\u00fcr und gegen den DG-Ausbau. Daf\u00fcr sprechen Instandhaltungsma\u00dfnahmen, die in diesem Zug mit vorgenommen werden k\u00f6nnen \u2013 das Dach w\u00e4re dann jedenfalls neu. Nat\u00fcrlich sind die jetzigen Bewohner des obersten Geschosses dagegen, es gibt aber auch Stimmen, die auf Bel\u00e4stigungen durch die Bauarbeiten hinweisen. Was gibt es hier zu beachten?<\/p>\n<h3>Was steht im Gesetz?<\/h3>\n<p>Das ist ein heikles Thema, da die \u201eAlt-WEG\u201c nicht immer Vorteile aus einem Dachgeschossausbau ziehen kann. Verkauft die WEG den Dachraum, kommt Geld in die Kasse, das die Instandhaltungsr\u00fccklage \u00fcber viele Jahre entlasten kann. Dann k\u00f6nnen Instandhaltungsstaus z.B. an der Fassade oder der Haustechnik ohne Sonderumlagen beseitigt werden. Bei DG- Ausbauarbeiten ist ein gew\u00fcnschter Einfluss der WEG im Vorfeld festzuschreiben; sp\u00e4ter kann hier nicht mehr nachgesteuert werden! H\u00e4ufig werden DG-Rohlinge w\u00e4hrend der Ausbaus weiter verkauft, d.h. es kommen Eigent\u00fcmer in die Gemeinschaft, die zuvor nicht bekannt waren. Der K\u00e4ufer des DG-Rohling agiert dann wie ein Bautr\u00e4ger, zieht also einen Teil seinen Gewinnes aus geringen Baukosten. In wieweit die Eigent\u00fcmergemeinschaft dann das Recht hat, bei mangelhafter Bauausf\u00fchrung am Gemeinschaftseigentum einzugreifen, ist h\u00f6chst fraglich und f\u00fchrt schnell zu rechtlichen Auseinandersetzungen. In jedem Fall wird in die alte Bausubstanz eingegriffen: Das Treppenhaus, Elektro, Heizung und Sanit\u00e4rleitungen m\u00fcssen in das DG verl\u00e4ngert werden, die Heizungsanlage ist ggf. zu erweitern. Vielleicht wird neben jedes Treppenhaus noch ein Aufzug in den Hof gestellt. Zur Fertigstellung des Ausbaus m\u00fcsste die Alt-WEG eigentlich auch noch eine Sicherheit aus dem DG-Rohling-Verkauf haben, um etwaige M\u00e4ngel aus einer Abnahme des ge\u00e4nderten Gemeinschaftseigentums einfordern zu k\u00f6nnen.<\/p>\n<h3>Und wie stehen Sie dazu?<\/h3>\n<p>F\u00fcr die WEG ist abzuwiegen, ob sich durch den DG- Ausbau tats\u00e4chlich eine Verbesserung ergibt. Besteht kein Instandsetzungsstau, gibt es ggf. keinen Grund, einen vielleicht noch genutzten alten Dachspeicher zu opfern. In jedem Fall kommt ein neues St\u00fcck Gemeinschaftseigentum auf die WEG zu, das zur Fertigstellung sicherlich nicht mangelfrei ist. Die M\u00e4ngelbeseitigung muss eingefordert werden, Gew\u00e4hrleistungsanspr\u00fcche sind durchzusetzen. Gibt es hierzu keine klaren Regelungen in der neu zu verfassenden Teilungserkl\u00e4rung, ist \u00c4rger vorprogrammiert. Dagegen bietet es sich f\u00fcr ein Haus, bei dem das Dach sanierungsbed\u00fcrftig ist, geradezu an, das DG zu verkaufen um dies im Zuge des Ausbaus instand setzen zu lassen. Dreh- und Angelpunkt sind klare Regelungen im Vorfeld, damit die WEG handlungsf\u00e4hig bleibt.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr und gegen einen Ausbau des Dachgeschosses sprechen innerhalb einer WEG viele Gr\u00fcnde. Welche Aspekte es f\u00fcr Eigent\u00fcmer zu beachten gilt, erfahren Sie hier.<\/p>\n","protected":false},"author":1,"featured_media":1486,"comment_status":"closed","ping_status":"open","sticky":false,"template":"page-with-right-sidebar","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[75,76,77,78,11],"post_series":[],"class_list":["post-1449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tagesspiegel","tag-dachgeschoss","tag-instandhaltungsstau","tag-instandsetzung","tag-sonderumlage","tag-weg","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Was eine WEG bei einem Dachausbau beachten sollte - P\u00b2 Ingenieure<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was eine WEG bei einem Dachausbau beachten sollte - P\u00b2 Ingenieure\" \/>\n<meta property=\"og:description\" content=\"F\u00fcr und gegen einen Ausbau des Dachgeschosses sprechen innerhalb einer WEG viele Gr\u00fcnde. Welche Aspekte es f\u00fcr Eigent\u00fcmer zu beachten gilt, erfahren Sie hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00b2 Ingenieure\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-10T17:59:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"945\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/\"},\"author\":{\"name\":\"Paul\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/f97c631d0ec288ddc753f40a90d3809b\"},\"headline\":\"Was eine WEG bei einem Dachausbau beachten sollte\",\"datePublished\":\"2018-03-10T17:59:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/\"},\"wordCount\":464,\"publisher\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg\",\"keywords\":[\"Dachgeschoss\",\"Instandhaltungsstau\",\"Instandsetzung\",\"Sonderumlage\",\"WEG\"],\"articleSection\":[\"Tagesspiegel\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/\",\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/\",\"name\":\"Was eine WEG bei einem Dachausbau beachten sollte - P\u00b2 Ingenieure\",\"isPartOf\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg\",\"datePublished\":\"2018-03-10T17:59:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#primaryimage\",\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg\",\"contentUrl\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg\",\"width\":945,\"height\":350,\"caption\":\"Tagesspiegel Icon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.p2-ingenieure.de\/gut\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was eine WEG bei einem Dachausbau beachten sollte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#website\",\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/\",\"name\":\"P\u00b2 Ingenieure\",\"description\":\"Ingenieurb\u00fcro Sabine und Manfred Puche\",\"publisher\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.p2-ingenieure.de\/gut\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#organization\",\"name\":\"P\u00b2 Ingenieure\",\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2025\/02\/cropped-logo200x200.png\",\"contentUrl\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2025\/02\/cropped-logo200x200.png\",\"width\":512,\"height\":512,\"caption\":\"P\u00b2 Ingenieure\"},\"image\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/f97c631d0ec288ddc753f40a90d3809b\",\"name\":\"Paul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2d82a344fc8c5bf8fe56df9cbca897eddd43ae86d04b0228884f9aa72ea5d153?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2d82a344fc8c5bf8fe56df9cbca897eddd43ae86d04b0228884f9aa72ea5d153?s=96&d=mm&r=g\",\"caption\":\"Paul\"},\"sameAs\":[\"https:\/\/www.p2-ingenieure.de\/gut\"],\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/author\/paul\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was eine WEG bei einem Dachausbau beachten sollte - P\u00b2 Ingenieure","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/","og_locale":"de_DE","og_type":"article","og_title":"Was eine WEG bei einem Dachausbau beachten sollte - P\u00b2 Ingenieure","og_description":"F\u00fcr und gegen einen Ausbau des Dachgeschosses sprechen innerhalb einer WEG viele Gr\u00fcnde. Welche Aspekte es f\u00fcr Eigent\u00fcmer zu beachten gilt, erfahren Sie hier.","og_url":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/","og_site_name":"P\u00b2 Ingenieure","article_published_time":"2018-03-10T17:59:11+00:00","og_image":[{"width":945,"height":350,"url":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg","type":"image\/jpeg"}],"author":"Paul","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Paul","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#article","isPartOf":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/"},"author":{"name":"Paul","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/f97c631d0ec288ddc753f40a90d3809b"},"headline":"Was eine WEG bei einem Dachausbau beachten sollte","datePublished":"2018-03-10T17:59:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/"},"wordCount":464,"publisher":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/#organization"},"image":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg","keywords":["Dachgeschoss","Instandhaltungsstau","Instandsetzung","Sonderumlage","WEG"],"articleSection":["Tagesspiegel"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/","url":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/","name":"Was eine WEG bei einem Dachausbau beachten sollte - P\u00b2 Ingenieure","isPartOf":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#primaryimage"},"image":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg","datePublished":"2018-03-10T17:59:11+00:00","breadcrumb":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#primaryimage","url":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg","contentUrl":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg","width":945,"height":350,"caption":"Tagesspiegel Icon"},{"@type":"BreadcrumbList","@id":"https:\/\/www.p2-ingenieure.de\/gut\/2018\/03\/10\/was-eine-weg-bei-einem-dachausbau-beachten-sollte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.p2-ingenieure.de\/gut\/"},{"@type":"ListItem","position":2,"name":"Was eine WEG bei einem Dachausbau beachten sollte"}]},{"@type":"WebSite","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#website","url":"https:\/\/www.p2-ingenieure.de\/gut\/","name":"P\u00b2 Ingenieure","description":"Ingenieurb\u00fcro Sabine und Manfred Puche","publisher":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.p2-ingenieure.de\/gut\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#organization","name":"P\u00b2 Ingenieure","url":"https:\/\/www.p2-ingenieure.de\/gut\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/logo\/image\/","url":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2025\/02\/cropped-logo200x200.png","contentUrl":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2025\/02\/cropped-logo200x200.png","width":512,"height":512,"caption":"P\u00b2 Ingenieure"},"image":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/f97c631d0ec288ddc753f40a90d3809b","name":"Paul","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2d82a344fc8c5bf8fe56df9cbca897eddd43ae86d04b0228884f9aa72ea5d153?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d82a344fc8c5bf8fe56df9cbca897eddd43ae86d04b0228884f9aa72ea5d153?s=96&d=mm&r=g","caption":"Paul"},"sameAs":["https:\/\/www.p2-ingenieure.de\/gut"],"url":"https:\/\/www.p2-ingenieure.de\/gut\/author\/paul\/"}]}},"_links":{"self":[{"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/posts\/1449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/comments?post=1449"}],"version-history":[{"count":0,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/posts\/1449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/media\/1486"}],"wp:attachment":[{"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/media?parent=1449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/categories?post=1449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/tags?post=1449"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/post_series?post=1449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}