{"id":1854,"date":"2019-04-09T05:42:52","date_gmt":"2019-04-09T04:42:52","guid":{"rendered":"http:\/\/www.p2-ingenieure.de\/wordpress\/?p=1854"},"modified":"2019-04-09T05:42:52","modified_gmt":"2019-04-09T04:42:52","slug":"schimmel-am-leichten-holzdach","status":"publish","type":"post","link":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/","title":{"rendered":"Schimmel am Garagendach aus Holz"},"content":{"rendered":"\n<p><em>erschienen im April 2019 im Tagesspiegel<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Was steht ins Haus?<\/h3>\n\n\n\n<p>Vor ca. 3 Jahren haben wir ein Einfamilienhaus mit an geschlossener Garage bauen lassen. In der Garage zeigen sich an der abgeh\u00e4ngten Decke seit einigen Wochen Schimmelflecken mit gelb verf\u00e4rbten R\u00e4ndern. Das Dach selbst ist eine leichte, flache, Holz- Konstruktion, mit Dachpappe gedeckt. Zwischen den Holzbalken wurde ged\u00e4mmt, da die Garage beheizt ist. Da es im letzten Jahr wenig geregnet hat, erscheint uns eine Undichtigkeit eher unwahrscheinlich. Aber ist nicht Schimmel in der Garage auch ungew\u00f6hnlich? Dort ist es doch eher trocken. Was k\u00f6nnen wir nun tun?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Was steht im Gesetz?<\/h3>\n\n\n\n<p>Dachundichtigkeiten lassen sich von Kondens- oder Tauwassersch\u00e4den recht einfach abgrenzen. Steht kein Eimer unter dem Dach, dann handelt es sich wohl um Tauwasser. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p>Beplankung, damfdichte Folie, W\u00e4rmed\u00e4mmung, Dachbahn <\/p><\/blockquote>\n\n\n\n<p><strong>Die Schimmelbildung <\/strong>zeigt, dass sich Wasser auf der abgeh\u00e4ngte Decke angesammelt hat. Die gelben R\u00e4nder deuten auf so viel Feuchtigkeit hin, dass es abgetropft sein muss. Der Gips und das Papier der Trockenbauplatten neigen durch die organischen Bestandteile zum Schimmeln, wenn das stehende Wasser abtrocknet. <\/p>\n\n\n\n<p><strong>Die Tauwasserbildung<\/strong> an der Dachunterseite zeigt die Schw\u00e4chen und Empfindlichkeit der leichten Holzdachkonstruktion auf; Die Dachbahnen auf der Au\u00dfenseite sind dampfdichter, als die raumseitige Beplankung.<\/p>\n\n\n\n<p>Auch wenn dort eine Dampfbrems- Folie eingezogen wurde, ist es eine bauphysikalisch labile Bauart. Aus der Bauphase (feuchtes Holz) und der Garagennutzung (warme Luft enth\u00e4lt viel Feuchtigkeit) str\u00f6mt und diffundiert Wasserdampf in die D\u00e4mmung. Dieser kann aber nicht nach au\u00dfen entweichen. Die D\u00e4mmung bewirkt im Winter einen Temperaturabfall in der Dachkonstruktion, so dass aus der feuchten Luft in der D\u00e4mmung Wassertropfen ausfallen. Dieses Feuchtigkeit ist dann f\u00fcr die Schimmelbildung in der abgeh\u00e4ngten Decke verantwortlich. Im Sommer kann sie meist nicht austrocknen, da das Bitumendach dampfdicht ist. Ebenso ist der Weg in den Raum durch den dichten Aufbau nach innen versperrt. So kann es \u00fcber ein paar Winter hinweg zur Auffeuchtung kommen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Und wie stehen Sie dazu?<\/h3>\n\n\n\n<p>Es ist ein bekannter Konstruktionsfehler, der seit vielen Jahren h\u00e4ufig untersch\u00e4tzt wird. Ein raumseitiger dichter Abschluss verhindert das Austrocknen etwaiger Feuchtigkeit im D\u00e4mmpaket der leichten Holzdachkonstruktionen. Daher werden seit Jahren raumseitig \u201eundichte\u201c feuchtevariable Folien eingesetzt, die eine m\u00f6gliche Austrocknung unterst\u00fctzen. Das richtige Konstruktionsprinzip jedoch ist ein bel\u00fcftetes Dach \u2013 dann wird die Feuchtigkeit der D\u00e4mmebene unterhalb der Dachabdichtung herausgel\u00fcftet \u2013 \u00e4hnlich wie bei einem Steildach. Weiterhin soll die Konstruktion nach oben m\u00f6glichst offenporig sein. Die gerne verwendeten OSB-Platten bestehen jedoch zu einem gro\u00dfen Teil aus Kleber, der die Unterkonstruktion f\u00fcr die Bitumenbahnen weiter dampfdicht macht. Eine Brettschalung w\u00e4re die bessere Alternative.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie Feuchtigkeit an einem abgedichteten Flachdach mit OSB-Schalung zu Schimmelbildung f\u00fchren kann.<\/p>\n","protected":false},"author":1,"featured_media":1486,"comment_status":"closed","ping_status":"open","sticky":false,"template":"page-with-right-sidebar","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[59,106,107,20,108,96,109,8,70,10,11],"post_series":[],"class_list":["post-1854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tagesspiegel","tag-dachabdichtung","tag-dachbahn","tag-dampfdichtigkeit","tag-feuchtigkeit","tag-flecken","tag-garage","tag-osb-platten","tag-schimmel","tag-schimmelbildung","tag-waermedaemmung","tag-weg","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Schimmel am Garagendach aus Holz - P\u00b2 Ingenieure<\/title>\n<meta name=\"description\" content=\"Warum kann Feuchtigkeit an einem abgedichteten Flachdach mit OSB-Schalung zu Schimmelbildung f\u00fchren? Hier erfahren sie es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schimmel am Garagendach aus Holz - P\u00b2 Ingenieure\" \/>\n<meta property=\"og:description\" content=\"Warum kann Feuchtigkeit an einem abgedichteten Flachdach mit OSB-Schalung zu Schimmelbildung f\u00fchren? Hier erfahren sie es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00b2 Ingenieure\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-09T04:42:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"945\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/\"},\"author\":{\"name\":\"Paul\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/f97c631d0ec288ddc753f40a90d3809b\"},\"headline\":\"Schimmel am Garagendach aus Holz\",\"datePublished\":\"2019-04-09T04:42:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/\"},\"wordCount\":450,\"publisher\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg\",\"keywords\":[\"Dachabdichtung\",\"Dachbahn\",\"Dampfdichtigkeit\",\"Feuchtigkeit\",\"Flecken\",\"Garage\",\"OSB-Platten\",\"Schimmel\",\"Schimmelbildung\",\"W\u00e4rmed\u00e4mmung\",\"WEG\"],\"articleSection\":[\"Tagesspiegel\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/\",\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/\",\"name\":\"Schimmel am Garagendach aus Holz - P\u00b2 Ingenieure\",\"isPartOf\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg\",\"datePublished\":\"2019-04-09T04:42:52+00:00\",\"description\":\"Warum kann Feuchtigkeit an einem abgedichteten Flachdach mit OSB-Schalung zu Schimmelbildung f\u00fchren? Hier erfahren sie es.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#primaryimage\",\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg\",\"contentUrl\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg\",\"width\":945,\"height\":350,\"caption\":\"Tagesspiegel Icon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.p2-ingenieure.de\/gut\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schimmel am Garagendach aus Holz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#website\",\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/\",\"name\":\"P\u00b2 Ingenieure\",\"description\":\"Ingenieurb\u00fcro Sabine und Manfred Puche\",\"publisher\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.p2-ingenieure.de\/gut\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#organization\",\"name\":\"P\u00b2 Ingenieure\",\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2025\/02\/cropped-logo200x200.png\",\"contentUrl\":\"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2025\/02\/cropped-logo200x200.png\",\"width\":512,\"height\":512,\"caption\":\"P\u00b2 Ingenieure\"},\"image\":{\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/f97c631d0ec288ddc753f40a90d3809b\",\"name\":\"Paul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2d82a344fc8c5bf8fe56df9cbca897eddd43ae86d04b0228884f9aa72ea5d153?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2d82a344fc8c5bf8fe56df9cbca897eddd43ae86d04b0228884f9aa72ea5d153?s=96&d=mm&r=g\",\"caption\":\"Paul\"},\"sameAs\":[\"https:\/\/www.p2-ingenieure.de\/gut\"],\"url\":\"https:\/\/www.p2-ingenieure.de\/gut\/author\/paul\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schimmel am Garagendach aus Holz - P\u00b2 Ingenieure","description":"Warum kann Feuchtigkeit an einem abgedichteten Flachdach mit OSB-Schalung zu Schimmelbildung f\u00fchren? Hier erfahren sie es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/","og_locale":"de_DE","og_type":"article","og_title":"Schimmel am Garagendach aus Holz - P\u00b2 Ingenieure","og_description":"Warum kann Feuchtigkeit an einem abgedichteten Flachdach mit OSB-Schalung zu Schimmelbildung f\u00fchren? Hier erfahren sie es.","og_url":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/","og_site_name":"P\u00b2 Ingenieure","article_published_time":"2019-04-09T04:42:52+00:00","og_image":[{"width":945,"height":350,"url":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg","type":"image\/jpeg"}],"author":"Paul","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Paul","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#article","isPartOf":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/"},"author":{"name":"Paul","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/f97c631d0ec288ddc753f40a90d3809b"},"headline":"Schimmel am Garagendach aus Holz","datePublished":"2019-04-09T04:42:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/"},"wordCount":450,"publisher":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/#organization"},"image":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#primaryimage"},"thumbnailUrl":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg","keywords":["Dachabdichtung","Dachbahn","Dampfdichtigkeit","Feuchtigkeit","Flecken","Garage","OSB-Platten","Schimmel","Schimmelbildung","W\u00e4rmed\u00e4mmung","WEG"],"articleSection":["Tagesspiegel"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/","url":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/","name":"Schimmel am Garagendach aus Holz - P\u00b2 Ingenieure","isPartOf":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#primaryimage"},"image":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#primaryimage"},"thumbnailUrl":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg","datePublished":"2019-04-09T04:42:52+00:00","description":"Warum kann Feuchtigkeit an einem abgedichteten Flachdach mit OSB-Schalung zu Schimmelbildung f\u00fchren? Hier erfahren sie es.","breadcrumb":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#primaryimage","url":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg","contentUrl":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2018\/03\/TSP-bild945x350-1.jpg","width":945,"height":350,"caption":"Tagesspiegel Icon"},{"@type":"BreadcrumbList","@id":"https:\/\/www.p2-ingenieure.de\/gut\/2019\/04\/09\/schimmel-am-leichten-holzdach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.p2-ingenieure.de\/gut\/"},{"@type":"ListItem","position":2,"name":"Schimmel am Garagendach aus Holz"}]},{"@type":"WebSite","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#website","url":"https:\/\/www.p2-ingenieure.de\/gut\/","name":"P\u00b2 Ingenieure","description":"Ingenieurb\u00fcro Sabine und Manfred Puche","publisher":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.p2-ingenieure.de\/gut\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#organization","name":"P\u00b2 Ingenieure","url":"https:\/\/www.p2-ingenieure.de\/gut\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/logo\/image\/","url":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2025\/02\/cropped-logo200x200.png","contentUrl":"https:\/\/www.p2-ingenieure.de\/gut\/wp-content\/uploads\/2025\/02\/cropped-logo200x200.png","width":512,"height":512,"caption":"P\u00b2 Ingenieure"},"image":{"@id":"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/f97c631d0ec288ddc753f40a90d3809b","name":"Paul","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.p2-ingenieure.de\/gut\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2d82a344fc8c5bf8fe56df9cbca897eddd43ae86d04b0228884f9aa72ea5d153?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d82a344fc8c5bf8fe56df9cbca897eddd43ae86d04b0228884f9aa72ea5d153?s=96&d=mm&r=g","caption":"Paul"},"sameAs":["https:\/\/www.p2-ingenieure.de\/gut"],"url":"https:\/\/www.p2-ingenieure.de\/gut\/author\/paul\/"}]}},"_links":{"self":[{"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/posts\/1854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/comments?post=1854"}],"version-history":[{"count":0,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/posts\/1854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/media\/1486"}],"wp:attachment":[{"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/media?parent=1854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/categories?post=1854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/tags?post=1854"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/www.p2-ingenieure.de\/gut\/wp-json\/wp\/v2\/post_series?post=1854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}